{"id":5050,"count":1,"description":"","link":"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/","name":"Dobradi\u00e7a vai e vem inox pre\u00e7o","slug":"dobradica-vai-e-vem-inox-preco","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arquivo de Dobradi\u00e7a vai e vem inox pre\u00e7o - Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arquivo de Dobradi\u00e7a vai e vem inox pre\u00e7o - Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/\",\"url\":\"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/\",\"name\":\"Arquivo de Dobradi\u00e7a vai e vem inox pre\u00e7o - Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.coimbra.com.br\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/www.coimbra.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dobradi\u00e7a vai e vem inox pre\u00e7o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.coimbra.com.br\/blog\/#website\",\"url\":\"https:\/\/www.coimbra.com.br\/blog\/\",\"name\":\"Blog\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.coimbra.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.coimbra.com.br\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.coimbra.com.br\/blog\/#organization\",\"name\":\"Blog\",\"url\":\"https:\/\/www.coimbra.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/www.coimbra.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.coimbra.com.br\/blog\/wp-content\/uploads\/2025\/11\/logo-_1_.png\",\"contentUrl\":\"https:\/\/www.coimbra.com.br\/blog\/wp-content\/uploads\/2025\/11\/logo-_1_.png\",\"width\":180,\"height\":85,\"caption\":\"Blog\"},\"image\":{\"@id\":\"https:\/\/www.coimbra.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arquivo de Dobradi\u00e7a vai e vem inox pre\u00e7o - Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/","og_locale":"pt_BR","og_type":"article","og_title":"Arquivo de Dobradi\u00e7a vai e vem inox pre\u00e7o - Blog","og_url":"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/","og_site_name":"Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/","url":"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/","name":"Arquivo de Dobradi\u00e7a vai e vem inox pre\u00e7o - Blog","isPartOf":{"@id":"https:\/\/www.coimbra.com.br\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.coimbra.com.br\/blog\/tag\/dobradica-vai-e-vem-inox-preco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/www.coimbra.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Dobradi\u00e7a vai e vem inox pre\u00e7o"}]},{"@type":"WebSite","@id":"https:\/\/www.coimbra.com.br\/blog\/#website","url":"https:\/\/www.coimbra.com.br\/blog\/","name":"Blog","description":"","publisher":{"@id":"https:\/\/www.coimbra.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.coimbra.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.coimbra.com.br\/blog\/#organization","name":"Blog","url":"https:\/\/www.coimbra.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.coimbra.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.coimbra.com.br\/blog\/wp-content\/uploads\/2025\/11\/logo-_1_.png","contentUrl":"https:\/\/www.coimbra.com.br\/blog\/wp-content\/uploads\/2025\/11\/logo-_1_.png","width":180,"height":85,"caption":"Blog"},"image":{"@id":"https:\/\/www.coimbra.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.coimbra.com.br\/blog\/wp-json\/wp\/v2\/tags\/5050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.coimbra.com.br\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.coimbra.com.br\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.coimbra.com.br\/blog\/wp-json\/wp\/v2\/posts?tags=5050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}